{"id":13571,"date":"2024-03-11T07:49:35","date_gmt":"2024-03-11T06:49:35","guid":{"rendered":"https:\/\/mestra.es\/producto\/cepillos\/"},"modified":"2025-03-26T09:53:43","modified_gmt":"2025-03-26T08:53:43","slug":"cepillos","status":"publish","type":"product","link":"https:\/\/mestra.es\/fr\/producto\/cepillos\/","title":{"rendered":"Brosses"},"content":{"rendered":"<p>Brosse et disque en toile de coton pour sablage, polissage et finition.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brosse et disque en toile de coton pour sablage, polissage et finition.<\/p>\n","protected":false},"featured_media":7401,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1306],"product_tag":[],"class_list":["post-13571","product","type-product","status-publish","has-post-thumbnail","product_cat-pinceaux-feutres","pa_tipo-bague-en-plastique","pa_tipo-brosses-a-main","pa_tipo-essieu-monte","pa_tipo-lignes","first","instock","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brosse et disque en toile de coton | MESTRA<\/title>\n<meta name=\"description\" content=\"En MESTRA disponemos brosse et disque en toile de coton. Consulta nuestro cat\u00e1logo de aparatolog\u00eda dental y haz ya tu pedido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mestra.es\/fr\/producto\/cepillos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brosse et disque en toile de coton | MESTRA\" \/>\n<meta property=\"og:description\" content=\"En MESTRA disponemos brosse et disque en toile de coton. Consulta nuestro cat\u00e1logo de aparatolog\u00eda dental y haz ya tu pedido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mestra.es\/fr\/producto\/cepillos\/\" \/>\n<meta property=\"og:site_name\" content=\"Talleres Mestra\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T08:53:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mestra.es\/wp-content\/uploads\/2024\/03\/gruce.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/\",\"url\":\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/\",\"name\":\"Brosse et disque en toile de coton | MESTRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mestra.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/gruce.jpg\",\"datePublished\":\"2024-03-11T06:49:35+00:00\",\"dateModified\":\"2025-03-26T08:53:43+00:00\",\"description\":\"En MESTRA disponemos brosse et disque en toile de coton. Consulta nuestro cat\u00e1logo de aparatolog\u00eda dental y haz ya tu pedido.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mestra.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/gruce.jpg\",\"contentUrl\":\"https:\\\/\\\/mestra.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/gruce.jpg\",\"width\":600,\"height\":600,\"caption\":\"Cep\u00ecllos y discos de tela\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/producto\\\/cepillos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mestra.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/mestra.es\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brosses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mestra.es\\\/fr\\\/\",\"name\":\"Talleres Mestra\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mestra.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/#organization\",\"name\":\"Talleres Mestra\",\"url\":\"https:\\\/\\\/mestra.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mestra.es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo_mestra.png\",\"contentUrl\":\"https:\\\/\\\/mestra.es\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo_mestra.png\",\"width\":300,\"height\":170,\"caption\":\"Talleres Mestra\"},\"image\":{\"@id\":\"https:\\\/\\\/mestra.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"080408 \/ ... \/ 060482\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brosse et disque en toile de coton | MESTRA","description":"En MESTRA disponemos brosse et disque en toile de coton. Consulta nuestro cat\u00e1logo de aparatolog\u00eda dental y haz ya tu pedido.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mestra.es\/fr\/producto\/cepillos\/","og_locale":"fr_FR","og_type":"article","og_title":"Brosse et disque en toile de coton | MESTRA","og_description":"En MESTRA disponemos brosse et disque en toile de coton. Consulta nuestro cat\u00e1logo de aparatolog\u00eda dental y haz ya tu pedido.","og_url":"https:\/\/mestra.es\/fr\/producto\/cepillos\/","og_site_name":"Talleres Mestra","article_modified_time":"2025-03-26T08:53:43+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/mestra.es\/wp-content\/uploads\/2024\/03\/gruce.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mestra.es\/fr\/producto\/cepillos\/","url":"https:\/\/mestra.es\/fr\/producto\/cepillos\/","name":"Brosse et disque en toile de coton | MESTRA","isPartOf":{"@id":"https:\/\/mestra.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mestra.es\/fr\/producto\/cepillos\/#primaryimage"},"image":{"@id":"https:\/\/mestra.es\/fr\/producto\/cepillos\/#primaryimage"},"thumbnailUrl":"https:\/\/mestra.es\/wp-content\/uploads\/2024\/03\/gruce.jpg","datePublished":"2024-03-11T06:49:35+00:00","dateModified":"2025-03-26T08:53:43+00:00","description":"En MESTRA disponemos brosse et disque en toile de coton. Consulta nuestro cat\u00e1logo de aparatolog\u00eda dental y haz ya tu pedido.","breadcrumb":{"@id":"https:\/\/mestra.es\/fr\/producto\/cepillos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mestra.es\/fr\/producto\/cepillos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mestra.es\/fr\/producto\/cepillos\/#primaryimage","url":"https:\/\/mestra.es\/wp-content\/uploads\/2024\/03\/gruce.jpg","contentUrl":"https:\/\/mestra.es\/wp-content\/uploads\/2024\/03\/gruce.jpg","width":600,"height":600,"caption":"Cep\u00ecllos y discos de tela"},{"@type":"BreadcrumbList","@id":"https:\/\/mestra.es\/fr\/producto\/cepillos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mestra.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/mestra.es\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Brosses"}]},{"@type":"WebSite","@id":"https:\/\/mestra.es\/fr\/#website","url":"https:\/\/mestra.es\/fr\/","name":"Talleres Mestra","description":"","publisher":{"@id":"https:\/\/mestra.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mestra.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mestra.es\/fr\/#organization","name":"Talleres Mestra","url":"https:\/\/mestra.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mestra.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mestra.es\/wp-content\/uploads\/2024\/05\/logo_mestra.png","contentUrl":"https:\/\/mestra.es\/wp-content\/uploads\/2024\/05\/logo_mestra.png","width":300,"height":170,"caption":"Talleres Mestra"},"image":{"@id":"https:\/\/mestra.es\/fr\/#\/schema\/logo\/image\/"}}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"080408 \/ ... \/ 060482","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/product\/13571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/media\/7401"}],"wp:attachment":[{"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/media?parent=13571"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/product_brand?post=13571"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/product_cat?post=13571"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mestra.es\/fr\/wp-json\/wp\/v2\/product_tag?post=13571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}